{"id":143211,"date":"2021-05-17T10:29:20","date_gmt":"2021-05-17T08:29:20","guid":{"rendered":"https:\/\/comunicacion.umh.es\/?p=143211"},"modified":"2021-05-17T12:09:50","modified_gmt":"2021-05-17T10:09:50","slug":"estudiantes-participan-en-una-jornada-virtual-con-representantes-de-la-empresa-enagas","status":"publish","type":"post","link":"https:\/\/comunicacion.umh.es\/ca\/2021\/05\/17\/estudiantes-participan-en-una-jornada-virtual-con-representantes-de-la-empresa-enagas\/","title":{"rendered":"<span lang=\"es\">(Espa\u00f1ol) Estudiantes participan en una jornada virtual con representantes de la empresa Enag\u00e1s<\/span>"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-ca\">Ho sent, per\u00f2 aquesta entrada nom\u00e9s est\u00e0 disponible en <a href=\"https:\/\/comunicacion.umh.es\/es\/wp-json\/wp\/v2\/posts\/143211\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Espanyol Europeu<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ho sent, per\u00f2 aquesta entrada nom\u00e9s est\u00e0 disponible en Espanyol Europeu.<\/p>\n","protected":false},"author":2693,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_links_to":"","_links_to_target":""},"categories":[43],"tags":[],"_links":{"self":[{"href":"https:\/\/comunicacion.umh.es\/ca\/wp-json\/wp\/v2\/posts\/143211"}],"collection":[{"href":"https:\/\/comunicacion.umh.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacion.umh.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacion.umh.es\/ca\/wp-json\/wp\/v2\/users\/2693"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacion.umh.es\/ca\/wp-json\/wp\/v2\/comments?post=143211"}],"version-history":[{"count":0,"href":"https:\/\/comunicacion.umh.es\/ca\/wp-json\/wp\/v2\/posts\/143211\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacion.umh.es\/ca\/wp-json\/wp\/v2\/media?parent=143211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacion.umh.es\/ca\/wp-json\/wp\/v2\/categories?post=143211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacion.umh.es\/ca\/wp-json\/wp\/v2\/tags?post=143211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}